{"id":3179,"date":"2024-04-13T18:59:04","date_gmt":"2024-04-13T18:59:04","guid":{"rendered":"https:\/\/chateau3fontaines.com\/?p=3179"},"modified":"2025-04-28T09:48:46","modified_gmt":"2025-04-28T09:48:46","slug":"team-building-activity-ideas-vaucluse-seminar-avignon-region","status":"publish","type":"post","link":"https:\/\/chateau3fontaines.com\/en\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/","title":{"rendered":"Team building Vaucluse"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3179\" class=\"elementor elementor-3179\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d777e8e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d777e8e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a521599\" data-id=\"a521599\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64ad1c2 elementor-widget elementor-widget-heading\" data-id=\"64ad1c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos id\u00e9es d'activit\u00e9s de team building dans le Vaucluse et s\u00e9minaire d'entreprise autour de la r\u00e9gion d'Avignon<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb37994 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb37994\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e94136d\" data-id=\"e94136d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4455000a elementor-widget elementor-widget-text-editor\" data-id=\"4455000a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Avignon, au c\u0153ur du Vaucluse, est un\u00a0<\/span><b>\u00e9crin de culture et d&rsquo;histoire<\/b><span style=\"font-weight: 400;\">, offrant un terrain de jeu vaste pour les challenges de team building. Situ\u00e9es dans un domaine d&rsquo;exception, les 3 Fontaines se sont impos\u00e9es comme un lieu incontournable pour proposer un environnement propice \u00e0 des\u00a0<\/span><b>exp\u00e9riences uniques<\/b><span style=\"font-weight: 400;\">\u00a0qui unissent les liens professionnels.<\/span><br \/><!-- notionvc: 9cfc2605-1194-4c08-8086-a9160103fc95 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-784c8012 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"784c8012\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-339a25b3\" data-id=\"339a25b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c61d7a0 elementor-widget elementor-widget-heading\" data-id=\"7c61d7a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vous souhaitez organiser un \u00e9v\u00e9nement d'entreprise ?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76deca0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76deca0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc87e69\" data-id=\"cc87e69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58b423c elementor-widget elementor-widget-text-editor\" data-id=\"58b423c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La r\u00e9gion d&rsquo;Avignon regorge\u00a0<\/span><b>d&rsquo;opportunit\u00e9s exceptionnelles<\/b><span style=\"font-weight: 400;\">\u00a0pour transformer votre simple r\u00e9union professionnelle en une exp\u00e9rience m\u00e9morable pour votre team. Qu&rsquo;il s&rsquo;agisse d&rsquo;un s\u00e9minaire strat\u00e9gique, d&rsquo;une journ\u00e9e de coh\u00e9sion ou d&rsquo;un incentive pour r\u00e9compenser vos collaborateurs, le Vaucluse offre un cadre exceptionnel combinant richesse culturelle, beaut\u00e9s naturelles et gastronomie renomm\u00e9e.<br \/><br \/><\/span><span style=\"font-weight: 400;\">Notre \u00e9quipe d&rsquo;experts en \u00e9v\u00e9nementiel se tient \u00e0 votre disposition pour concevoir un\u00a0<\/span><b>programme sur mesure<\/b><span style=\"font-weight: 400;\">, adapt\u00e9 aux objectifs sp\u00e9cifiques de votre entreprise. De la logistique \u00e0 l&rsquo;animation des activit\u00e9s, nous prenons en charge tous les aspects de votre projet pour vous permettre de vous concentrer sur l&rsquo;essentiel : renforcer la coh\u00e9sion de votre \u00e9quipe et stimuler sa motivation.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49ed994 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49ed994\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc82bb7\" data-id=\"bc82bb7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-860c52e elementor-widget elementor-widget-heading\" data-id=\"860c52e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Team building dans le Vaucluse autour du vin<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42c257f6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42c257f6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-526a3fc0\" data-id=\"526a3fc0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67afc9ee elementor-widget elementor-widget-text-editor\" data-id=\"67afc9ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Cette activit\u00e9 invite les participants \u00e0 plonger dans l&rsquo;univers viticole de la r\u00e9gion, avec des visites de vignobles, des d\u00e9gustations guid\u00e9es par des sommeliers, et des ateliers sur l&rsquo;art de la vinification. C&rsquo;est une excellente mani\u00e8re de favoriser la collaboration tout en d\u00e9couvrant les traditions locales au sein d&rsquo;une entreprise.<\/span><\/p><p><span style=\"font-weight: 400;\">Imaginez votre team parcourant les coteaux ensoleill\u00e9s des C\u00f4tes du Rh\u00f4ne, apprenant \u00e0 reconna\u00eetre les c\u00e9pages et \u00e0 appr\u00e9cier les\u00a0<\/span><b>nuances aromatiques des grands crus<\/b><span style=\"font-weight: 400;\">\u00a0locaux. Cette immersion dans le monde viticole stimule les \u00e9changes informels et permet de d\u00e9couvrir de nouvelles facettes de vos collaborateurs dans un contexte d\u00e9tendu, loin du stress quotidien du bureau.<\/span><\/p><p><span style=\"font-weight: 400;\">Au-del\u00e0 de la simple d\u00e9gustation, cela peut inclure un challenge de cr\u00e9ation d&rsquo;assemblage, o\u00f9 chaque team cr\u00e9e son propre vin, encourag\u00e9e par les conseils d&rsquo;experts. Cela favorise non seulement la cr\u00e9ativit\u00e9 mais aussi la prise de d\u00e9cision collective.<\/span><\/p><p><span style=\"font-weight: 400;\">La r\u00e9gion d&rsquo;Avignon, entour\u00e9e de prestigieuses appellations comme <\/span><a href=\"https:\/\/www.chateauneuf.com\/\"><span style=\"font-weight: 400;\">Ch\u00e2teauneuf-du-Pape<\/span><\/a><span style=\"font-weight: 400;\">, Gigondas, Vacqueyras ou Beaumes-de-Venise, est le cadre id\u00e9al pour un team building \u0153nologique. Entre ville et campagne, vos collaborateurs pourront visiter des caves centenaires, participer \u00e0 des vendanges (selon la saison) ou m\u00eame cr\u00e9er l&rsquo;\u00e9tiquette personnalis\u00e9e de leur cuv\u00e9e d&rsquo;\u00e9quipe. Ces activit\u00e9s permettent d&rsquo;aborder de fa\u00e7on ludique des notions de travail collectif, d&rsquo;excellence et de respect des traditions.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-409658c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"409658c5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1370221e\" data-id=\"1370221e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56efde44 elementor-widget elementor-widget-heading\" data-id=\"56efde44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le rallye en 2CV \u00e0 l'Isle sur Sorgue<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-277d4b55 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"277d4b55\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-146ea16e\" data-id=\"146ea16e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52527448 elementor-widget elementor-widget-text-editor\" data-id=\"52527448\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Rien ne dit mieux aventure et coh\u00e9sion qu&rsquo;un rallye en 2CV \u00e0 travers les paysages pittoresques de l&rsquo;Isle sur Sorgue. Cette activit\u00e9 stimule la communication et la strat\u00e9gie d&rsquo;\u00e9quipe, tout en offrant un moment de d\u00e9tente et de plaisir partag\u00e9. Cette qu\u00eate les m\u00e8ne \u00e0 d\u00e9couvrir des lieux historiques, des march\u00e9s locaux et des paysages \u00e0 couper le souffle, renfor\u00e7ant leur coh\u00e9sion \u00e0 travers une exp\u00e9rience commune inoubliable.<\/span><\/p><p><span style=\"font-weight: 400;\">Au volant de ces voitures embl\u00e9matiques, les \u00e9quipes devront relever des d\u00e9fis, r\u00e9soudre des \u00e9nigmes et trouver leur chemin \u00e0 travers les\u00a0<\/span><b>ruelles pittoresques de cette ville<\/b><span style=\"font-weight: 400;\">\u00a0surnomm\u00e9e \u00ab\u00a0la Venise comtadine\u00a0\u00bb. Ce type d&rsquo;animation favorise naturellement la collaboration, la prise de d\u00e9cision collective et la gestion du temps, tout en cr\u00e9ant des souvenirs durables que vos collaborateurs \u00e9voqueront longtemps apr\u00e8s l&rsquo;event.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00a848e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00a848e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6680c32\" data-id=\"6680c32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b27037a elementor-widget elementor-widget-heading\" data-id=\"b27037a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Des id\u00e9es d'activit\u00e9s de coh\u00e9sion nature \u00e0 Avignon et ces alentours au sein d'une entreprise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64dac4a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64dac4a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e7c0983\" data-id=\"6e7c0983\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30050629 elementor-widget elementor-widget-text-editor\" data-id=\"30050629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Notre r\u00e9gion est b\u00e9nie par la nature, proposant une vari\u00e9t\u00e9 d&rsquo;activit\u00e9s en ext\u00e9rieur. Les randonn\u00e9es guid\u00e9es \u00e0 travers les sentiers du Luberon permettent de d\u00e9couvrir la beaut\u00e9 naturelle de la r\u00e9gion tout en encourageant l&rsquo;esprit d&rsquo;\u00e9quipe. Les parcours d&rsquo;accrobranche, quant \u00e0 eux, mettent \u00e0 l&rsquo;\u00e9preuve la confiance et l&rsquo;entraide au sein des groupes.<br \/><br \/><\/span><span style=\"font-weight: 400;\">\u00c0 seulement quelques kilom\u00e8tres du centre historique d&rsquo;Avignon, votre team pourra s&rsquo;\u00e9vader dans des\u00a0<\/span><b>paysages vari\u00e9s et majestueux<\/b><span style=\"font-weight: 400;\">\u00a0: des berges ombrag\u00e9es de la Sorgue aux falaises d&rsquo;ocre du Colorado proven\u00e7al, en passant par les lavandes du plateau de Sault. Ces cadres exceptionnels offrent un terrain de jeu id\u00e9al pour des activit\u00e9s ludiques et f\u00e9d\u00e9ratrices qui renforcent la coh\u00e9sion entre collaborateurs.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa986c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa986c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-07ced91\" data-id=\"07ced91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7429bb1 elementor-widget elementor-widget-heading\" data-id=\"7429bb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Randonn\u00e9e d\u00e9couverte avec guide local<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4aed1e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4aed1e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c0b4af7\" data-id=\"c0b4af7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bf6589 elementor-widget elementor-widget-text-editor\" data-id=\"3bf6589\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"font-weight: 400;\">Organisez une randonn\u00e9e personnalis\u00e9e avec un guide connaissant les sentiers secrets du Vaucluse. Cette activit\u00e9 combine effort physique mod\u00e9r\u00e9 et d\u00e9couverte culturelle, permettant \u00e0 votre \u00e9quipe de se ressourcer tout en apprenant sur la faune, la flore et le patrimoine local. Pour les teams plus sportives, le Mont Ventoux, surnomm\u00e9 le\u00a0<\/span><b>\u00ab\u00a0G\u00e9ant de Provence\u00a0\u00bb<\/b><span style=\"font-weight: 400;\">, offre un d\u00e9fi stimulant et une vue panoramique exceptionnelle, r\u00e9compense ultime de l&rsquo;effort collectif.<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-934ceec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"934ceec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3513fc9\" data-id=\"3513fc9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ee549d elementor-widget elementor-widget-heading\" data-id=\"4ee549d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Challenge d'orientation en pleine nature\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b2b376 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b2b376\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d69e634\" data-id=\"d69e634\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bdfb94 elementor-widget elementor-widget-text-editor\" data-id=\"5bdfb94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Munis de cartes et de boussoles, vos collaborateurs devront travailler ensemble pour retrouver leur chemin \u00e0 travers les paysages naturels entourant Avignon. Cette activit\u00e9 d\u00e9veloppe la communication, la\u00a0<\/span><b>planification strat\u00e9gique<\/b><span style=\"font-weight: 400;\">\u00a0et la r\u00e9solution de probl\u00e8mes, tout en cr\u00e9ant une exp\u00e9rience partag\u00e9e qui soude les liens au sein de l&rsquo;\u00e9quipe.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff79dfb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ff79dfb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-746b175\" data-id=\"746b175\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9bd12e elementor-widget elementor-widget-heading\" data-id=\"f9bd12e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le rallye nautique en kayak<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3123fa4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3123fa4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5312861\" data-id=\"5312861\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d61f67 elementor-widget elementor-widget-text-editor\" data-id=\"5d61f67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Cela permet une \u00e9chapp\u00e9e hors du temps sur les eaux claires de la Sorgue. Travailler ensemble pour naviguer le cours d&rsquo;eau teste la communication et la synchronisation de l&rsquo;\u00e9quipe, tout en offrant des moments de rire et de d\u00e9tente.<br \/><br \/><\/span><span style=\"font-weight: 400;\">Imaginez votre team pagayant en harmonie \u00e0 travers les m\u00e9andres de la rivi\u00e8re \u00e9meraude, d\u00e9couvrant la richesse de l&rsquo;\u00e9cosyst\u00e8me aquatique et les moulins historiques qui bordent ses rives. Cette activit\u00e9 aquatique est particuli\u00e8rement appr\u00e9ci\u00e9e pendant les chaudes journ\u00e9es d&rsquo;\u00e9t\u00e9, offrant une alternative rafra\u00eechissante aux animations classiques de team building. Elle combine parfaitement effort physique mod\u00e9r\u00e9, coordination collective et moments de contemplation de la nature proven\u00e7ale.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e82a6be elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e82a6be\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d992b1\" data-id=\"2d992b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9092b8a elementor-widget elementor-widget-heading\" data-id=\"9092b8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Team building Escape Game<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9683449 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9683449\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dbfff6b\" data-id=\"dbfff6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00d0a69 elementor-widget elementor-widget-text-editor\" data-id=\"00d0a69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Concevoir un escape game dans l&rsquo;enceinte des 3 Fontaines ou ses jardins offre une aventure captivante. Les \u00e9quipes doivent collaborer \u00e9troitement pour d\u00e9crypter des \u00e9nigmes li\u00e9es \u00e0 l&rsquo;histoire du lieu et de la r\u00e9gion, unifiant leurs efforts pour atteindre un objectif commun dans un temps limit\u00e9.<br \/><br \/><\/span><span style=\"font-weight: 400;\">Cette activit\u00e9 stimule particuli\u00e8rement la communication, la r\u00e9solution de probl\u00e8mes et la gestion du stress positif. Pour renforcer l&rsquo;exp\u00e9rience, les \u00e9nigmes peuvent \u00eatre th\u00e9matis\u00e9es autour de l&rsquo;histoire d&rsquo;Avignon, des Papes ou des traditions proven\u00e7ales, ajoutant ainsi une dimension culturelle \u00e0 ce d\u00e9fi ludique. Les jeux d&rsquo;\u00e9vasion r\u00e9v\u00e8lent souvent des qualit\u00e9s insoup\u00e7onn\u00e9es chez les membres de votre team, permettant \u00e0 chacun de briller selon ses comp\u00e9tences sp\u00e9cifiques.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6dc03c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6dc03c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f72d7c9\" data-id=\"f72d7c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4df8761 elementor-widget elementor-widget-heading\" data-id=\"4df8761\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'histoire de Ch\u00e2teauneuf du Pape<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e685b4d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e685b4d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c255fd\" data-id=\"7c255fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9ad464 elementor-widget elementor-widget-text-editor\" data-id=\"b9ad464\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Plongez dans le c\u0153ur historique de la viticulture proven\u00e7ale avec une visite guid\u00e9e de Ch\u00e2teauneuf du Pape. Cette activit\u00e9 permet non seulement une d\u00e9gustation des vins embl\u00e9matiques de la r\u00e9gion mais aussi une immersion dans l&rsquo;histoire et les traditions qui ont fa\u00e7onn\u00e9 ce terroir d&rsquo;exception. Les visiteurs apprendront comment le climat, le sol, et le savoir-faire des vignerons contribuent \u00e0 la renomm\u00e9e mondiale de ces vins. Une telle activit\u00e9 renforce le sentiment d&rsquo;appartenance \u00e0 un groupe, en partageant des connaissances et des plaisirs sensoriels.<br \/><br \/><\/span><span style=\"font-weight: 400;\">\u00c0 seulement 15 kilom\u00e8tres d&rsquo;Avignon, ce village perch\u00e9 domin\u00e9 par les ruines du ch\u00e2teau papal offre un cadre authentique pour un <\/span><a href=\"https:\/\/chateau3fontaines.com\/en\/2024\/06\/24\/the-5-key-steps-for-a-successful-business-seminar-in-2024\/\"><span style=\"font-weight: 400;\">s\u00e9minaire combinant business et plaisir<\/span><\/a><span style=\"font-weight: 400;\">. Votre team pourra alterner sessions de travail dans des caves historiques et moments de d\u00e9tente face aux panoramas spectaculaires sur les vignobles. Cette immersion dans un terroir d&rsquo;exception favorise les discussions informelles et renforce le sentiment d&rsquo;appartenance \u00e0 votre entreprise.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5427885 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5427885\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba9680a\" data-id=\"ba9680a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02d1c9d elementor-widget elementor-widget-heading\" data-id=\"02d1c9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Team building gourmand \u00e0 Pernes-les-Fontaines<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-582c7ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"582c7ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c81dd8c\" data-id=\"c81dd8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58759f9 elementor-widget elementor-widget-text-editor\" data-id=\"58759f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Rien ne rassemble plus que la cuisine<\/b><span style=\"font-weight: 400;\">, et les 3 Fontaines l&rsquo;ont bien compris. Organiser un \u00e9v\u00e8nement culinaire permet aux employ\u00e9s de mettre la main \u00e0 la p\u00e2te sous la direction de chefs locaux. Que ce soit lors d&rsquo;un atelier de fabrication de tapenade, de cours de cuisine sur les plats traditionnels proven\u00e7aux, ou d&rsquo;une comp\u00e9tition amicale autour de la meilleure recette de ratatouille, chaque participant d\u00e9couvrira les saveurs de la Provence tout en d\u00e9veloppant des amiti\u00e9s fortes avec ses coll\u00e8gues. C&rsquo;est une activit\u00e9 parfaite pour stimuler la cr\u00e9ativit\u00e9, encourager la communication, et savourer le plaisir du travail d&rsquo;\u00e9quipe.<br \/><br \/><\/span><span style=\"font-weight: 400;\">La gastronomie proven\u00e7ale, avec ses ingr\u00e9dients frais et ses recettes ensoleill\u00e9es, constitue un formidable vecteur de partage et de convivialit\u00e9. Votre team pourra \u00e9galement partir \u00e0 la d\u00e9couverte des march\u00e9s locaux, s\u00e9lectionner les meilleurs produits et relever le d\u00e9fi de pr\u00e9parer ensemble un repas complet. Cette exp\u00e9rience immersive r\u00e9v\u00e8le souvent des talents cach\u00e9s et cr\u00e9e des liens durables entre collaborateurs.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f0f3d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f0f3d9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1094cc1\" data-id=\"1094cc1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-584e24a elementor-widget elementor-widget-heading\" data-id=\"584e24a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Envie de booster votre \u00e9v\u00e9nement d'entreprise ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-789413c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"789413c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4be1e01\" data-id=\"4be1e01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15b3d84 elementor-widget elementor-widget-text-editor\" data-id=\"15b3d84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Cherchez-vous \u00e0\u00a0<\/span><b>sortir des sentiers battus<\/b><span style=\"font-weight: 400;\">\u00a0pour votre prochain s\u00e9minaire d&rsquo;entreprise ? La r\u00e9gion d&rsquo;Avignon offre des possibilit\u00e9s infinies pour transformer une simple r\u00e9union professionnelle en une exp\u00e9rience m\u00e9morable qui renforcera la coh\u00e9sion de votre \u00e9quipe.<br \/><br \/><\/span><span style=\"font-weight: 400;\">Nos experts en team building con\u00e7oivent des programmes sur mesure <\/span><a href=\"https:\/\/chateau3fontaines.com\/en\/2024\/06\/15\/how-to-choose-the-team-building-activities-adapted-to-your-goals\/\"><span style=\"font-weight: 400;\">qui r\u00e9pondent pr\u00e9cis\u00e9ment \u00e0 vos objectifs<\/span><\/a><span style=\"font-weight: 400;\"> : am\u00e9liorer la communication, d\u00e9velopper la cr\u00e9ativit\u00e9, renforcer la confiance mutuelle ou simplement r\u00e9compenser vos collaborateurs pour leurs performances. Chaque activit\u00e9 est soigneusement s\u00e9lectionn\u00e9e pour cr\u00e9er un impact durable sur votre culture d&rsquo;entreprise et les relations au sein de votre team.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f40ecf8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f40ecf8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13f9c57\" data-id=\"13f9c57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7448bb2 elementor-widget elementor-widget-heading\" data-id=\"7448bb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos id\u00e9es de team building gr\u00e2ce au chant<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-acc5c23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"acc5c23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c701c78\" data-id=\"c701c78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38e8d0a elementor-widget elementor-widget-text-editor\" data-id=\"38e8d0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Le chant a ce\u00a0<\/span><b>pouvoir unique de souder les gens<\/b><span style=\"font-weight: 400;\">, en cr\u00e9ant une harmonie collective \u00e0 partir de voix individuelles. Organiser un atelier de chant aux 3 Fontaines permet de vivre cette activit\u00e9 magique, o\u00f9 les participants, guid\u00e9s par un chef de ch\u0153ur professionnel, apprennent \u00e0 coordonner leurs voix pour interpr\u00e9ter ensemble des morceaux choisis. Cette activit\u00e9 renforce l&rsquo;\u00e9coute mutuelle, la confiance en soi et en les autres, et laisse des souvenirs inoubliables.<br \/><br \/><\/span><span style=\"font-weight: 400;\">Avignon, ville du festival de th\u00e9\u00e2tre reconnu internationalement, est naturellement un lieu privil\u00e9gi\u00e9 pour des activit\u00e9s artistiques. Votre team pourra b\u00e9n\u00e9ficier de l&rsquo;expertise de professionnels du spectacle pour d\u00e9velopper des comp\u00e9tences transf\u00e9rables au monde de l&rsquo;entreprise : projection de la voix, pr\u00e9sence sc\u00e9nique, \u00e9coute active et cr\u00e9ation collective. La r\u00e9gion compte de nombreux artistes de talent qui peuvent animer ces ateliers dans des lieux d&rsquo;exception, comme le clo\u00eetre des Carmes ou les jardins des 3 Fontaines.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0bfa6c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0bfa6c5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e5ccd6\" data-id=\"2e5ccd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-380b963 elementor-widget elementor-widget-heading\" data-id=\"380b963\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le team building proven\u00e7al : apprendre les traditions de Provence<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f24da2f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f24da2f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8223b12\" data-id=\"8223b12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4fe5f2 elementor-widget elementor-widget-text-editor\" data-id=\"e4fe5f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La Provence est riche de traditions et de savoir-faire ancestraux. Inviter vos collaborateurs \u00e0 d\u00e9couvrir ces tr\u00e9sors culturels \u00e0 travers des ateliers de fabrication de savon de Marseille, de confection de santons, ou encore de danse folklorique proven\u00e7ale, c&rsquo;est une immersion dans l&rsquo;\u00e2me de cette r\u00e9gion. Ces traditions, enracin\u00e9es dans le terroir et l&rsquo;histoire, sont l&rsquo;occasion d&rsquo;apprendre, de partager, et de vivre ensemble des moments forts, renfor\u00e7ant l&rsquo;esprit d&rsquo;\u00e9quipe.<br \/><br \/><\/span><span style=\"font-weight: 400;\">Entre Avignon et la ville d&rsquo;Orange, votre team pourra \u00e9galement d\u00e9couvrir les\u00a0<\/span><b>secrets ancestraux des produits embl\u00e9matiques<\/b><span style=\"font-weight: 400;\">\u00a0qui font la renomm\u00e9e de la Provence. Ces activit\u00e9s sensorielles cr\u00e9ent des souvenirs marquants et permettent de valoriser des notions essentielles en entreprise comme l&rsquo;authenticit\u00e9, la patience et l&rsquo;excellence artisanale.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06cd87e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06cd87e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13c80bc\" data-id=\"13c80bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-818a112 elementor-widget elementor-widget-heading\" data-id=\"818a112\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le team building th\u00e9\u00e2tre : Le festival d'Avignon aux 3 Fontaines<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d1f32a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d1f32a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e31ee4\" data-id=\"1e31ee4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4234b4a elementor-widget elementor-widget-text-editor\" data-id=\"4234b4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Le festival d&rsquo;Avignon est un rendez-vous culturel incontournable. Organiser un atelier de th\u00e9\u00e2tre en lien avec cet \u00e9v\u00e9nement aux 3 Fontaines permet de profiter de l&rsquo;effervescence artistique ambiante pour inspirer et motiver vos \u00e9quipes. Les participants peuvent travailler sur des pi\u00e8ces, improviser ou m\u00eame cr\u00e9er une petite production \u00e0 pr\u00e9senter en fin de s\u00e9minaire. Cet atelier peut d\u00e9velopper l&rsquo;expression personnelle et collective, la prise de parole en public, et stimuler la cr\u00e9ativit\u00e9 dans un cadre ludique et bienveillant.<br \/><br \/><\/span><span style=\"font-weight: 400;\">La ville d&rsquo;Avignon, avec son patrimoine architectural exceptionnel et son ambiance culturelle unique, constitue une source d&rsquo;inspiration in\u00e9puisable pour les activit\u00e9s cr\u00e9atives. Votre team pourra s&rsquo;initier \u00e0 l&rsquo;improvisation th\u00e9\u00e2trale, \u00e0 l&rsquo;\u00e9loquence ou \u00e0 la cr\u00e9ation de sayn\u00e8tes illustrant la vie de l&rsquo;entreprise. Ces exercices, encadr\u00e9s par des com\u00e9diens professionnels, d\u00e9veloppent des comp\u00e9tences essentielles dans le monde professionnel : aisance oratoire, adaptabilit\u00e9 et intelligence collective.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71081f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71081f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-210c621\" data-id=\"210c621\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f30c43 elementor-widget elementor-widget-heading\" data-id=\"4f30c43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9couverte du patrimoine romain \u00e0 Orange<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61dd692 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61dd692\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-872be07\" data-id=\"872be07\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62c8a90 elementor-widget elementor-widget-text-editor\" data-id=\"62c8a90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">\u00c0 seulement 30 minutes d&rsquo;Avignon, la ville d&rsquo;Orange abrite des\u00a0<\/span><b>tr\u00e9sors de l&rsquo;\u00e9poque romaine<\/b><span style=\"font-weight: 400;\">, dont le c\u00e9l\u00e8bre Th\u00e9\u00e2tre Antique, l&rsquo;un des mieux conserv\u00e9s au monde. Organisez pour votre team une visite priv\u00e9e suivie d&rsquo;un atelier sur l&rsquo;art oratoire dans ce cadre mill\u00e9naire. Cette immersion dans l&rsquo;histoire romaine peut \u00eatre l&rsquo;occasion d&rsquo;explorer les parall\u00e8les entre l&rsquo;organisation de cette civilisation et les principes modernes de management et de leadership.<br \/><br \/><\/span><span style=\"font-weight: 400;\">Ce site exceptionnel peut \u00e9galement accueillir des \u00e9v\u00e9nements d&rsquo;entreprise uniques, comme un d\u00eener de gala sous les \u00e9toiles ou une conf\u00e9rence dans un d\u00e9cor charg\u00e9 d&rsquo;histoire. L&rsquo;acoustique remarquable du th\u00e9\u00e2tre permet m\u00eame d&rsquo;organiser des prises de parole sans microphone, une exp\u00e9rience impressionnante pour vos collaborateurs qui renforcera l&rsquo;impact de vos messages cl\u00e9s.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ccf2e98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccf2e98\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55532fb\" data-id=\"55532fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35aeb35 elementor-widget elementor-widget-heading\" data-id=\"35aeb35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Soir\u00e9e inoubliable aux 3 Fontaines pour vos collaborateurs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f3da59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f3da59\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-485f256\" data-id=\"485f256\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d085a9 elementor-widget elementor-widget-text-editor\" data-id=\"9d085a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Pour cl\u00f4turer un s\u00e9minaire ou des activit\u00e9s de team building ludiques, quoi de mieux qu&rsquo;une\u00a0<\/span><b>soir\u00e9e d&rsquo;entreprise exceptionnelle<\/b><span style=\"font-weight: 400;\">\u00a0dans l&rsquo;enceinte des 3 Fontaines ? Imaginez un\u00a0<\/span><b>d\u00eener gastronomique sous les \u00e9toiles<\/b><span style=\"font-weight: 400;\">, dans les jardins illumin\u00e9s, ou une soir\u00e9e \u00e0 th\u00e8me dans l&rsquo;une des salles historiques, d\u00e9cor\u00e9e pour l&rsquo;occasion. Ces moments privil\u00e9gi\u00e9s permettent de c\u00e9l\u00e9brer les succ\u00e8s, de consolider les liens entre collaborateurs, et de laisser \u00e0 chacun des souvenirs m\u00e9morables.<br \/><br \/><\/span><span style=\"font-weight: 400;\">Notre \u00e9quipe event peut organiser des\u00a0<\/span><b>animations sur mesure pour votre soir\u00e9e<\/b><span style=\"font-weight: 400;\">\u00a0: d\u00e9gustation de vins locaux, spectacle de flamenco, concert acoustique ou DJ set pour danser jusqu&rsquo;au bout de la nuit. Ces moments de convivialit\u00e9 sont essentiels pour renforcer l&rsquo;esprit d&rsquo;\u00e9quipe et cr\u00e9er une culture d&rsquo;entreprise positive. Les vastes espaces des 3 Fontaines permettent d&rsquo;accueillir des groupes de toutes tailles, du comit\u00e9 de direction restreint \u00e0 l&rsquo;ensemble des collaborateurs d&rsquo;une grande entreprise.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d26a4f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d26a4f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e2a6821\" data-id=\"e2a6821\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c10106d elementor-widget elementor-widget-heading\" data-id=\"c10106d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un cadre d'exception pour vos s\u00e9minaires professionnels<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb04510 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb04510\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c5b6f8\" data-id=\"9c5b6f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c72b6f2 elementor-widget elementor-widget-text-editor\" data-id=\"c72b6f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Quelles sont les caract\u00e9ristiques qui distinguent les 3 Fontaines pour un s\u00e9minaire ? La premi\u00e8re est sans doute son cadre historique, qui inspire et stimule la cr\u00e9ativit\u00e9. Les salles majestueuses, les vastes terrains et les jardins minutieusement entretenus cr\u00e9ent un environnement propice \u00e0 la r\u00e9flexion, \u00e0 la d\u00e9tente, et \u00e0 la coh\u00e9sion de groupe.<\/span><\/p><p><span style=\"font-weight: 400;\">Ensuite, le domaine offre une multitude d&rsquo;espaces modulables adapt\u00e9s \u00e0 tout type d&rsquo;\u00e9v\u00e9nement : des s\u00e9minaires formels aux activit\u00e9s de team building plus d\u00e9tendues. Chaque espace peut \u00eatre personnalis\u00e9 pour r\u00e9pondre aux besoins sp\u00e9cifiques de vos collaborateurs, qu&rsquo;il s&rsquo;agisse d&rsquo;une grande conf\u00e9rence ou d&rsquo;un atelier intimiste.<\/span><\/p><p><span style=\"font-weight: 400;\">Situ\u00e9 \u00e0 proximit\u00e9 d&rsquo;Avignon, ce lieu d&rsquo;exception b\u00e9n\u00e9ficie d&rsquo;une\u00a0<\/span><b>accessibilit\u00e9 id\u00e9ale<\/b><span style=\"font-weight: 400;\">, avec une gare TGV reliant Paris en moins de 3 heures et un a\u00e9roport international \u00e0 15 minutes. Cette position centrale en fait un choix strat\u00e9gique pour rassembler des \u00e9quipes venant de diff\u00e9rentes r\u00e9gions ou m\u00eame de l&rsquo;\u00e9tranger.<\/span><\/p><p><span style=\"font-weight: 400;\">Le vaste parc paysager est un autre atout majeur. Il pr\u00e9sente une\u00a0<\/span><b>diversit\u00e9 exceptionnelle d&rsquo;essences<\/b><span style=\"font-weight: 400;\">\u00a0et d&rsquo;ombrages naturels, id\u00e9aux pour des pauses r\u00e9cr\u00e9atives ou des challenges en plein air. \u00c0 la tomb\u00e9e de la nuit, le parc r\u00e9ussit \u00e0 se transformer gr\u00e2ce \u00e0 un syst\u00e8me d&rsquo;\u00e9clairage sophistiqu\u00e9, cr\u00e9ant une atmosph\u00e8re f\u00e9erique pour les soir\u00e9es d&rsquo;entreprise.<\/span><\/p><p><span style=\"font-weight: 400;\">En somme, les 3 Fontaines pr\u00e9sentent un\u00a0<\/span><b>cadre idyllique pour des s\u00e9minaires d&rsquo;entreprise<\/b><span style=\"font-weight: 400;\">. Gr\u00e2ce \u00e0 sa riche palette d&rsquo;activit\u00e9s, son histoire fascinante, et ses installations de premier choix, chaque \u00e9v\u00e9nement devient une exp\u00e9rience inoubliable, renfor\u00e7ant les liens professionnels et personnels entre collaborateurs.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75bc17c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75bc17c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-845080d\" data-id=\"845080d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff43c20 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ff43c20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/chateau3fontaines.com\/en\/contact-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact us<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nos id\u00e9es d&rsquo;activit\u00e9s de team building dans le Vaucluse et s\u00e9minaire d&rsquo;entreprise autour de la r\u00e9gion d&rsquo;Avignon Avignon, au c\u0153ur du Vaucluse, est un\u00a0\u00e9crin de culture et d&rsquo;histoire, offrant un terrain de jeu vaste pour les challenges de team building. Situ\u00e9es dans un domaine d&rsquo;exception, les 3 Fontaines se sont impos\u00e9es comme un lieu incontournable &#8230; <a title=\"Team building Vaucluse\" class=\"read-more\" href=\"https:\/\/chateau3fontaines.com\/en\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/\" aria-label=\"Read more about Team building Vaucluse\">Read more<\/a><\/p>","protected":false},"author":10,"featured_media":3184,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Team building Vaucluse - Location salles de r\u00e9ception et parc<\/title>\n<meta name=\"description\" content=\"Avignon, au c\u0153ur du Vaucluse, est un \u00e9crin de culture et d\u2019histoire, offrant un terrain de jeu vaste pour les challenges de team building.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chateau3fontaines.com\/en\/2024\/04\/13\/team-building-activity-ideas-vaucluse-seminar-avignon-region\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Team building Vaucluse - Location salles de r\u00e9ception et parc\" \/>\n<meta property=\"og:description\" content=\"Avignon, au c\u0153ur du Vaucluse, est un \u00e9crin de culture et d\u2019histoire, offrant un terrain de jeu vaste pour les challenges de team building.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chateau3fontaines.com\/en\/2024\/04\/13\/team-building-activity-ideas-vaucluse-seminar-avignon-region\/\" \/>\n<meta property=\"og:site_name\" content=\"Location salles de r\u00e9ception et parc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100070023877597\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-13T18:59:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T09:48:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chateau3fontaines.com\/wp-content\/uploads\/2024\/03\/chateau-des-3-Fontaines-site-web-actualites-article-Pourquoi-choisir-un-chateau-pour-votre-prochain-team-building-dans-le-vaucluse-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment CATHERINE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment CATHERINE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/2024\\\/04\\\/13\\\/idees-activites-team-building-vaucluse-seminaire-region-avignon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/2024\\\/04\\\/13\\\/idees-activites-team-building-vaucluse-seminaire-region-avignon\\\/\"},\"author\":{\"name\":\"Cl\u00e9ment CATHERINE\",\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/#\\\/schema\\\/person\\\/017625881bb7829786b75f456b928a0c\"},\"headline\":\"Team building Vaucluse\",\"datePublished\":\"2024-04-13T18:59:04+00:00\",\"dateModified\":\"2025-04-28T09:48:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/2024\\\/04\\\/13\\\/idees-activites-team-building-vaucluse-seminaire-region-avignon\\\/\"},\"wordCount\":2793,\"publisher\":{\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/2024\\\/04\\\/13\\\/idees-activites-team-building-vaucluse-seminaire-region-avignon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chateau3fontaines.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/chateau-des-3-Fontaines-site-web-actualites-article-Pourquoi-choisir-un-chateau-pour-votre-prochain-team-building-dans-le-vaucluse-.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/2024\\\/04\\\/13\\\/idees-activites-team-building-vaucluse-seminaire-region-avignon\\\/\",\"url\":\"https:\\\/\\\/chateau3fontaines.com\\\/2024\\\/04\\\/13\\\/idees-activites-team-building-vaucluse-seminaire-region-avignon\\\/\",\"name\":\"Team building Vaucluse - Location salles de r\u00e9ception et parc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/2024\\\/04\\\/13\\\/idees-activites-team-building-vaucluse-seminaire-region-avignon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/2024\\\/04\\\/13\\\/idees-activites-team-building-vaucluse-seminaire-region-avignon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chateau3fontaines.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/chateau-des-3-Fontaines-site-web-actualites-article-Pourquoi-choisir-un-chateau-pour-votre-prochain-team-building-dans-le-vaucluse-.jpg\",\"datePublished\":\"2024-04-13T18:59:04+00:00\",\"dateModified\":\"2025-04-28T09:48:46+00:00\",\"description\":\"Avignon, au c\u0153ur du Vaucluse, est un \u00e9crin de culture et d\u2019histoire, offrant un terrain de jeu vaste pour les challenges de team building.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/2024\\\/04\\\/13\\\/idees-activites-team-building-vaucluse-seminaire-region-avignon\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chateau3fontaines.com\\\/2024\\\/04\\\/13\\\/idees-activites-team-building-vaucluse-seminaire-region-avignon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/2024\\\/04\\\/13\\\/idees-activites-team-building-vaucluse-seminaire-region-avignon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chateau3fontaines.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/chateau-des-3-Fontaines-site-web-actualites-article-Pourquoi-choisir-un-chateau-pour-votre-prochain-team-building-dans-le-vaucluse-.jpg\",\"contentUrl\":\"https:\\\/\\\/chateau3fontaines.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/chateau-des-3-Fontaines-site-web-actualites-article-Pourquoi-choisir-un-chateau-pour-votre-prochain-team-building-dans-le-vaucluse-.jpg\",\"width\":2000,\"height\":1125,\"caption\":\"Location salles de r\u00e9ception et parc - chateau-des-3-Fontaines-site-web-actualites-article-Pourquoi-choisir-un-chateau-pour-votre-prochain-team-building-dans-le-vaucluse-\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/2024\\\/04\\\/13\\\/idees-activites-team-building-vaucluse-seminaire-region-avignon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chateau3fontaines.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Team building Vaucluse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/#website\",\"url\":\"https:\\\/\\\/chateau3fontaines.com\\\/\",\"name\":\"Location salles de r\u00e9ception et parc\",\"description\":\"Pernes les Fontaines\",\"publisher\":{\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chateau3fontaines.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/#organization\",\"name\":\"Ch\u00e2teau des 3 Fontaines\",\"url\":\"https:\\\/\\\/chateau3fontaines.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chateau3fontaines.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/admin-ajax.php_.png\",\"contentUrl\":\"https:\\\/\\\/chateau3fontaines.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/admin-ajax.php_.png\",\"width\":160,\"height\":101,\"caption\":\"Ch\u00e2teau des 3 Fontaines\"},\"image\":{\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100070023877597\",\"https:\\\/\\\/www.instagram.com\\\/lechateaudestroisfontaines\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chateau3fontaines.com\\\/#\\\/schema\\\/person\\\/017625881bb7829786b75f456b928a0c\",\"name\":\"Cl\u00e9ment CATHERINE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/27b6ca5c1c10ae94c831af7e38e57b84a7fa73ed615c4a3fb53fca38621d07fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/27b6ca5c1c10ae94c831af7e38e57b84a7fa73ed615c4a3fb53fca38621d07fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/27b6ca5c1c10ae94c831af7e38e57b84a7fa73ed615c4a3fb53fca38621d07fa?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment CATHERINE\"},\"url\":\"https:\\\/\\\/chateau3fontaines.com\\\/en\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Team building Vaucluse - Location salles de r\u00e9ception et parc","description":"Avignon, au c\u0153ur du Vaucluse, est un \u00e9crin de culture et d\u2019histoire, offrant un terrain de jeu vaste pour les challenges de team building.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chateau3fontaines.com\/en\/2024\/04\/13\/team-building-activity-ideas-vaucluse-seminar-avignon-region\/","og_locale":"en_US","og_type":"article","og_title":"Team building Vaucluse - Location salles de r\u00e9ception et parc","og_description":"Avignon, au c\u0153ur du Vaucluse, est un \u00e9crin de culture et d\u2019histoire, offrant un terrain de jeu vaste pour les challenges de team building.","og_url":"https:\/\/chateau3fontaines.com\/en\/2024\/04\/13\/team-building-activity-ideas-vaucluse-seminar-avignon-region\/","og_site_name":"Location salles de r\u00e9ception et parc","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100070023877597","article_published_time":"2024-04-13T18:59:04+00:00","article_modified_time":"2025-04-28T09:48:46+00:00","og_image":[{"width":2000,"height":1125,"url":"https:\/\/chateau3fontaines.com\/wp-content\/uploads\/2024\/03\/chateau-des-3-Fontaines-site-web-actualites-article-Pourquoi-choisir-un-chateau-pour-votre-prochain-team-building-dans-le-vaucluse-.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment CATHERINE","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Cl\u00e9ment CATHERINE","Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chateau3fontaines.com\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/#article","isPartOf":{"@id":"https:\/\/chateau3fontaines.com\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/"},"author":{"name":"Cl\u00e9ment CATHERINE","@id":"https:\/\/chateau3fontaines.com\/#\/schema\/person\/017625881bb7829786b75f456b928a0c"},"headline":"Team building Vaucluse","datePublished":"2024-04-13T18:59:04+00:00","dateModified":"2025-04-28T09:48:46+00:00","mainEntityOfPage":{"@id":"https:\/\/chateau3fontaines.com\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/"},"wordCount":2793,"publisher":{"@id":"https:\/\/chateau3fontaines.com\/#organization"},"image":{"@id":"https:\/\/chateau3fontaines.com\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/#primaryimage"},"thumbnailUrl":"https:\/\/chateau3fontaines.com\/wp-content\/uploads\/2024\/03\/chateau-des-3-Fontaines-site-web-actualites-article-Pourquoi-choisir-un-chateau-pour-votre-prochain-team-building-dans-le-vaucluse-.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/chateau3fontaines.com\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/","url":"https:\/\/chateau3fontaines.com\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/","name":"Team building Vaucluse - Location salles de r\u00e9ception et parc","isPartOf":{"@id":"https:\/\/chateau3fontaines.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chateau3fontaines.com\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/#primaryimage"},"image":{"@id":"https:\/\/chateau3fontaines.com\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/#primaryimage"},"thumbnailUrl":"https:\/\/chateau3fontaines.com\/wp-content\/uploads\/2024\/03\/chateau-des-3-Fontaines-site-web-actualites-article-Pourquoi-choisir-un-chateau-pour-votre-prochain-team-building-dans-le-vaucluse-.jpg","datePublished":"2024-04-13T18:59:04+00:00","dateModified":"2025-04-28T09:48:46+00:00","description":"Avignon, au c\u0153ur du Vaucluse, est un \u00e9crin de culture et d\u2019histoire, offrant un terrain de jeu vaste pour les challenges de team building.","breadcrumb":{"@id":"https:\/\/chateau3fontaines.com\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chateau3fontaines.com\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/chateau3fontaines.com\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/#primaryimage","url":"https:\/\/chateau3fontaines.com\/wp-content\/uploads\/2024\/03\/chateau-des-3-Fontaines-site-web-actualites-article-Pourquoi-choisir-un-chateau-pour-votre-prochain-team-building-dans-le-vaucluse-.jpg","contentUrl":"https:\/\/chateau3fontaines.com\/wp-content\/uploads\/2024\/03\/chateau-des-3-Fontaines-site-web-actualites-article-Pourquoi-choisir-un-chateau-pour-votre-prochain-team-building-dans-le-vaucluse-.jpg","width":2000,"height":1125,"caption":"Location salles de r\u00e9ception et parc - chateau-des-3-Fontaines-site-web-actualites-article-Pourquoi-choisir-un-chateau-pour-votre-prochain-team-building-dans-le-vaucluse-"},{"@type":"BreadcrumbList","@id":"https:\/\/chateau3fontaines.com\/2024\/04\/13\/idees-activites-team-building-vaucluse-seminaire-region-avignon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chateau3fontaines.com\/"},{"@type":"ListItem","position":2,"name":"Team building Vaucluse"}]},{"@type":"WebSite","@id":"https:\/\/chateau3fontaines.com\/#website","url":"https:\/\/chateau3fontaines.com\/","name":"Hire of function rooms and park","description":"Pernes les Fontaines","publisher":{"@id":"https:\/\/chateau3fontaines.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chateau3fontaines.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/chateau3fontaines.com\/#organization","name":"Ch\u00e2teau des 3 Fontaines\u00a0","url":"https:\/\/chateau3fontaines.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/chateau3fontaines.com\/#\/schema\/logo\/image\/","url":"https:\/\/chateau3fontaines.com\/wp-content\/uploads\/2021\/08\/admin-ajax.php_.png","contentUrl":"https:\/\/chateau3fontaines.com\/wp-content\/uploads\/2021\/08\/admin-ajax.php_.png","width":160,"height":101,"caption":"Ch\u00e2teau des 3 Fontaines"},"image":{"@id":"https:\/\/chateau3fontaines.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100070023877597","https:\/\/www.instagram.com\/lechateaudestroisfontaines\/"]},{"@type":"Person","@id":"https:\/\/chateau3fontaines.com\/#\/schema\/person\/017625881bb7829786b75f456b928a0c","name":"Cl\u00e9ment CATHERINE","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/27b6ca5c1c10ae94c831af7e38e57b84a7fa73ed615c4a3fb53fca38621d07fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/27b6ca5c1c10ae94c831af7e38e57b84a7fa73ed615c4a3fb53fca38621d07fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/27b6ca5c1c10ae94c831af7e38e57b84a7fa73ed615c4a3fb53fca38621d07fa?s=96&d=mm&r=g","caption":"Cl\u00e9ment CATHERINE"},"url":"https:\/\/chateau3fontaines.com\/en"}]}},"_links":{"self":[{"href":"https:\/\/chateau3fontaines.com\/en\/wp-json\/wp\/v2\/posts\/3179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chateau3fontaines.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chateau3fontaines.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chateau3fontaines.com\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/chateau3fontaines.com\/en\/wp-json\/wp\/v2\/comments?post=3179"}],"version-history":[{"count":5,"href":"https:\/\/chateau3fontaines.com\/en\/wp-json\/wp\/v2\/posts\/3179\/revisions"}],"predecessor-version":[{"id":4403,"href":"https:\/\/chateau3fontaines.com\/en\/wp-json\/wp\/v2\/posts\/3179\/revisions\/4403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chateau3fontaines.com\/en\/wp-json\/wp\/v2\/media\/3184"}],"wp:attachment":[{"href":"https:\/\/chateau3fontaines.com\/en\/wp-json\/wp\/v2\/media?parent=3179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chateau3fontaines.com\/en\/wp-json\/wp\/v2\/categories?post=3179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chateau3fontaines.com\/en\/wp-json\/wp\/v2\/tags?post=3179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}